{"id":686,"count":1,"description":"","link":"https:\/\/vocilibereurss.fupress.net\/en\/tag\/metricalization\/","name":"Metricalization","slug":"metricalization","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/vocilibereurss.fupress.net\/en\/wp-json\/wp\/v2\/tags\/686"}],"collection":[{"href":"https:\/\/vocilibereurss.fupress.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/vocilibereurss.fupress.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/vocilibereurss.fupress.net\/en\/wp-json\/wp\/v2\/posts?tags=686"},{"href":"https:\/\/vocilibereurss.fupress.net\/en\/wp-json\/wp\/v2\/tribe_events?tags=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}